{"text_format":"1","workbook":"xlsx","n_sheets":4,"sheets":["Hoja1","GENERALES","Hoja3","CUMPLIMIENTO"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":0,"defined_names":0,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Hoja1","index":0,"n_rows":53,"n_cols":10,"rows_kept":53,"cut":false,"hidden":true,"merged":[[16,1,16,2],[16,3,16,4],[16,5,16,6]]}
["RESPONSABILIDAD_CIVIL","PROPERTY","INGENIERÍA","TRANSPORTE","VIDA_GRUPO","PRETENSIÓN"]
["PLO","INCENDIO","CONSTRUCCIÓN","BÁSICO","FXCC","DETERMINADA"]
["AMP_ADC_RC","AMP_ADC_PR",null,null,"AMP_ADC_VG","INDETERMINADA"]
["CLÍNICAS"]
["MÉDICAS"]
[]
[]
[]
[]
[]
["PLO","AMP_ADC_RC","CLÍNICAS","MÉDICAS","INCENDIO","AMP_ADC_PR","CONSTRUCCIÓN","BÁSICO","FXCC","AMP_ADC_VG"]
[4450788927,4450788927,624414098,624414098,7588225023,7588225023,3221180759,1E+19,1E+19,1E+19]
[]
[]
[]
[]
["PRODUCTO","Bajo",null,"Medio",null,"Alto"]
["PLO",0,1000000000,1000000001,10000000000,10000000001,1E+19]
["AMP_ADC_RC",0,1000000000,1000000001,10000000000,10000000001,1E+19]
["CLÍNICAS",0,500000000,500000001,2000000000,2000000001,1E+19]
["MÉDICAS",0,100000000,100000001,1000000000,1000000001,1E+19]
["INCENDIO",0,50000000000,50000000001,100000000000,100000000001,1E+19]
["AMP_ADC_PR",0,50000000000,50000000001,100000000000,100000000001,1E+19]
["CONSTRUCCIÓN",0,900000000,900000001,3000000000,3000000001,1E+19]
["TRANSPORTE BÁSICO",0,900000000,900000001,3000000000,3000000001,1E+19]
["FXCC",0,900000000,900000001,3000000000,3000000001,1E+19]
["AMP_ADC_VG",0,900000000,900000001,3000000000,3000000001,1E+19]
[]
[]
["COSTES MEDIO","BAJO","MEDIO","ALTO"]
["PLO",4000000,31000000,31000000]
["AMP_ADC_RC",2000000,2000000,2000000]
["CLÍNICAS",9000000,32000000,32000000]
["MÉDICAS",10000000,10000000,10000000]
["INCENDIO",9000000,9000000,9000000]
["AMP_ADC_PR",10000000,10000000,10000000]
["CONSTRUCCIÓN",9000000,41000000,74000000]
["TRANSPORTE BÁSICO",19000000,19000000,19000000]
["FXCC",30000000,30000000,30000000]
["AMP_ADC_VG",5000000,5000000,5000000]
[]
[]
["ALAE"]
["PLO",2100000]
["AMP_ADC_RC",2400000]
["CLÍNICAS",1300000]
["MÉDICAS",600000]
["INCENDIO",700000]
["AMP_ADC_PR",900000]
["CONSTRUCCIÓN",4600000]
["TRANSPORTE BÁSICO",1000000]
["FXCC",800000]
["AMP_ADC_VG",1300000]

{"sheet":"GENERALES","index":1,"n_rows":16,"n_cols":2,"rows_kept":16,"cut":false,"hidden":true,"merged":[]}
["Columna1","Columna2"]
["L.O.B.","RESPONSABILIDAD_CIVIL"]
["AMPARO","PLO"]
["PARTICIPACIÓN COMPAÑÍA COASEGURO CEDIDO",0.5]
["VALOR ASEGURADO TOTAL",1]
["VALOR ASEGURADO AMPARO",1]
["VALOR PRETENSIÓN VALIDADA",1]
["PML",{"$f":"MIN(B6:B7)*B4","v":0.5}]
["UMBRAL",{"$f":"IF(B3=\"PLO\",Hoja1!A12,IF(B3=\"AMP_ADC_RC\",Hoja1!B12,IF(B3=\"CLÍNICAS\",Hoja1!C12,IF(B3=\"MÉDICAS\",Hoja1!D12,IF(B3=\"INCENDIO\",Hoja1!E12,IF(B3=\"AMP_ADC_PR\",Hoja1!F12,IF(B3=\"CONSTRUCCIÓN\",Hoja1!G12,IF(B3=\"BÁSICO\",Hoja1!H12,IF(B3=\"FXCC\",Hoja1!I12,IF(B3=\"AMP_ADC_VG\",Hoja1!J12))))))))))","v":4450788927}]
["ATÍPICO?",{"$f":"IF(B7=\"\",\"NO\",IF(B8>B9,\"SI\",\"NO\"))","v":"NO"}]
["RESERVA ATÍPICO",{"$f":"IF(AND(B10=\"SI\",B3=\"INCENDIO\"),B8*0.0317,IF(AND(B10=\"SI\",B3=\"AMP_ADC_PR\"),B8*0.0317,IF(AND(B10=\"SI\",B3=\"CONSTRUCCIÓN\"),B8*0.2136,IF(AND(B10=\"SI\",B3=\"PLO\"),B8*0.0294,IF(AND(B10=\"SI\",B3=\"AMP_ADC_RC\"),B8*0.0294,IF(AND(B10=\"SI\",B3=\"CLÍNICAS\"),B8*0.0112,IF(AND(B10=\"SI\",B3=\"MÉDICAS\"),B8*0.0112)))))))","v":false}]
["CATE. VALOR ASEGURADO",{"$f":"IF(AND(B10=\"NO\",B3=\"INCENDIO\",B5<=Hoja1!C22),\"BAJO\",IF(AND(B10=\"NO\",B3=\"INCENDIO\",AND(B5>=Hoja1!D22),B5<=Hoja1!E22),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"INCENDIO\",B5>=Hoja1!F22),\"ALTO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_PR\",B5<=Hoja1!C23),\"BAJO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_PR\",AND(B5>Hoja1!D23),B5<=Hoja1!E23),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_PR\",B5>Hoja1!F23),\"ALTO\",IF(AND(B10=\"NO\",B3=\"CONSTRUCCIÓN\",B5<=Hoja1!C24),\"BAJO\",IF(AND(B10=\"NO\",B3=\"CONSTRUCCIÓN\",AND(B5>=Hoja1!D24),B5<=Hoja1!E24),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"CONSTRUCCIÓN\",B5>=Hoja1!F24),\"ALTO\",IF(AND(B10=\"NO\",B3=\"BÁSICO\",B5<=Hoja1!C25),\"BAJO\",IF(AND(B10=\"NO\",B3=\"BÁSICO\",AND(B5>=Hoja1!D25),B5<=Hoja1!E25),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"BÁSICO\",B5>=Hoja1!F25),\"ALTO\",IF(AND(B10=\"NO\",B3=\"FXCC\",B5<=Hoja1!C26),\"BAJO\",IF(AND(B10=\"NO\",B3=\"FXCC\",AND(B5>=Hoja1!D26),B5<=Hoja1!E26),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"FXCC\",B5>=Hoja1!F26),\"ALTO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_VG\",B5<=Hoja1!C27),\"BAJO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_VG\",AND(B5>=Hoja1!D27),B5<=Hoja1!E27),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_VG\",B5>=Hoja1!F27),\"ALTO\",IF(AND(B10=\"NO\",B3=\"PLO\",B5<=Hoja1!C18),\"BAJO\",IF(AND(B10=\"NO\",B3=\"PLO\",AND(B5>=Hoja1!D18),B5<=Hoja1!E18),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"PLO\",B5>=Hoja1!F18),\"ALTO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_RC\",B5<=Hoja1!C19),\"BAJO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_RC\",AND(B5>=Hoja1!D19),B5<=Hoja1!E19),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"AMP_ADC_RC\",B5>=Hoja1!F19),\"ALTO\",IF(AND(B10=\"NO\",B3=\"CLÍNICAS\",B5<=Hoja1!C20),\"BAJO\",IF(AND(B10=\"NO\",B3=\"CLÍNICAS\",AND(B5>=Hoja1!D20),B5<=Hoja1!E20),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"CLÍNICAS\",B5>=Hoja1!F20),\"ALTO\",IF(AND(B10=\"NO\",B3=\"MÉDICAS\",B5<=Hoja1!C21),\"BAJO\",IF(AND(B10=\"NO\",B3=\"MÉDICAS\",AND(B5>=Hoja1!D21),B5<=Hoja1!E21),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"MÉDICAS\",B5>=Hoja1!F21),\"ALTO\"))))))))))))))))))))))))))))))","v":"BAJO"}]
["RESERVA TÍPICO PARTICIPACIÓN COMPAÑÍA",{"$f":"IF(AND(B3=\"PLO\",B12=\"BAJO\"),Hoja1!B31,IF(AND(B3=\"PLO\",B12=\"MEDIO\"),Hoja1!C31,IF(AND(B3=\"PLO\",B12=\"ALTO\"),Hoja1!D31,IF(AND(B3=\"AMP_ADC_RC\",B12=\"BAJO\"),Hoja1!B32,IF(AND(B3=\"AMP_ADC_RC\",B12=\"MEDIO\"),Hoja1!C32,IF(AND(B3=\"AMP_ADC_RC\",B12=\"ALTO\"),Hoja1!D32,IF(AND(B3=\"CLÍNICAS\",B12=\"BAJO\"),Hoja1!B33,IF(AND(B3=\"CLÍNICAS\",B12=\"MEDIO\"),Hoja1!C33,IF(AND(B3=\"CLÍNICAS\",B12=\"ALTO\"),Hoja1!D33,IF(AND(B3=\"MÉDICAS\",B12=\"BAJO\"),Hoja1!B34,IF(AND(B3=\"MÉDICAS\",B12=\"MEDIO\"),Hoja1!C34,IF(AND(B3=\"MÉDICAS\",B12=\"ALTO\"),Hoja1!D34,IF(AND(B3=\"INCENDIO\",B12=\"BAJO\"),Hoja1!B35,IF(AND(B3=\"INCENDIO\",B12=\"MEDIO\"),Hoja1!C35,IF(AND(B3=\"INCENDIO\",B12=\"ALTO\"),Hoja1!D35,IF(AND(B3=\"AMP_ADC_PR\",B12=\"BAJO\"),Hoja1!B36,IF(AND(B3=\"AMP_ADC_PR\",B12=\"MEDIO\"),Hoja1!C36,IF(AND(B3=\"AMP_ADC_PR\",B12=\"ALTO\"),Hoja1!D36,IF(AND(B3=\"CONSTRUCCIÓN\",B12=\"BAJO\"),Hoja1!B37,IF(AND(B3=\"CONSTRUCCIÓN\",B12=\"MEDIO\"),Hoja1!C37,IF(AND(B3=\"CONSTRUCCIÓN\",B12=\"ALTO\"),Hoja1!D37,IF(AND(B3=\"BÁSICO\",B12=\"BAJO\"),Hoja1!B38,IF(AND(B3=\"BÁSICO\",B12=\"MEDIO\"),Hoja1!C38,IF(AND(B3=\"BÁSICO\",B12=\"ALTO\"),Hoja1!D38,IF(AND(B3=\"FXCC\",B12=\"BAJO\"),Hoja1!B39,IF(AND(B3=\"FXCC\",B12=\"MEDIO\"),Hoja1!C39,IF(AND(B3=\"FXCC\",B12=\"ALTO\"),Hoja1!D39,IF(AND(B3=\"AMP_ADC_VG\",B12=\"BAJO\"),Hoja1!B40,IF(AND(B3=\"AMP_ADC_VG\",B12=\"MEDIO\"),Hoja1!C40,IF(AND(B3=\"AMP_ADC_VG\",B12=\"ALTO\"),Hoja1!D40))))))))))))))))))))))))))))))","v":4000000}]
["RESERVA SINIESTRO TÍPICO AL 100%",{"$f":"B13/B4","v":8000000}]
["RESERVA TÍPICO ALAE PARTICIPACIÓN COMPAÑÍA",{"$f":"IF(B3=\"PLO\",Hoja1!B44,IF(B3=\"AMP_ADC_RC\",Hoja1!B45,IF(B3=\"CLÍNICAS\",Hoja1!B46,IF(B3=\"MÉDICAS\",Hoja1!B47,IF(B3=\"INCENDIO\",Hoja1!B48,IF(B3=\"AMP_ADC_PR\",Hoja1!B49,IF(B3=\"CONSTRUCCIÓN\",Hoja1!B50,IF(B3=\"BÁSICO\",Hoja1!B51,IF(B3=\"FXCC\",Hoja1!B52,IF(B3=\"AMP_ADC_VG\",Hoja1!B53))))))))))","v":2100000}]
["RESERVA ALAE TÍPICO AL 100%",{"$f":"B15/B4","v":4200000}]

{"sheet":"Hoja3","index":2,"n_rows":51,"n_cols":8,"rows_kept":51,"cut":false,"hidden":true,"merged":[[16,1,16,2],[16,3,16,4],[16,5,16,6]]}
["ESTATALES","PARTICULARES","SERVICIOS_PÚBLICOS","DISP_LEGALES","CAUCIONES_JUDICIALES","PRETENSIÓN"]
["E. CONTRACTUALES","P. CONTRACTUALES","S. CONTRACTUALES","DISP_LEGALES","CAUCIONES_JUDICIALES","DETERMINADA"]
["E. POSTCONTRACTUALES","P. POSTCONTRACTUALES","S. POSTCONTRACTUALES",null,null,"INDETERMINADA"]
[]
[]
[]
[]
[]
[]
[]
["E. CONTRACTUALES","E. POSTCONTRACTUALES","P. CONTRACTUALES","P. POSTCONTRACTUALES","S. CONTRACTUALES","S. POSTCONTRACTUALES","DISP_LEGALES","CAUCIONES_JUDICIALES"]
[15792651847,15792651847,10420236585,10420236585,4044144916,4044144916,1625353015,4044144916]
[]
[]
[]
[]
["PRODUCTO","Bajo",null,"Medio",null,"Alto"]
["E. CONTRACTUALES",0,600000000,600000001,1500000000,1500000001,1E+19]
["E. POSTCONTRACTUALES",0,600000000,600000001,1500000000,1500000001,1E+19]
["P. CONTRACTUALES",0,50000000,50000001,100000000,100000001,1E+19]
["P. POSTCONTRACTUALES",0,50000000,50000001,100000000,100000001,1E+19]
["S. CONTRACTUALES",0,100000000,100000001,1000000000,1000000001,1E+19]
["S. POSTCONTRACTUALES",0,100000000,100000001,1000000000,1000000001,1E+19]
["DISP_LEGALES",0,50000000,50000001,100000000,100000001,1E+19]
["CAUCIONES_JUDICIALES",0,50000000,50000001,100000000,100000001,1E+19]
[]
[]
[]
[]
["COSTES MEDIO","BAJO","MEDIO","ALTO",null,1000000001]
["E. CONTRACTUALES",13000000,37000000,91000000,null,1000000100]
["E. POSTCONTRACTUALES",22000000,27000000,67000000]
["P. CONTRACTUALES",6000000,11000000,41000000]
["P. POSTCONTRACTUALES",2000000,13000000,13000000]
["S. CONTRACTUALES",14000000,14000000,14000000]
["S. POSTCONTRACTUALES",16000000,16000000,16000000]
["DISP_LEGALES",8000000,25000000,55000000]
["CAUCIONES_JUDICIALES",9000000,45000000,80000000]
[]
[]
[]
[]
["ALAE"]
["E. CONTRACTUALES",4800000]
["E. POSTCONTRACTUALES",300000]
["P. CONTRACTUALES",2700000]
["P. POSTCONTRACTUALES",1300000]
["S. CONTRACTUALES",5200000]
["S. POSTCONTRACTUALES",1100000]
["DISP_LEGALES",3400000]
["CAUCIONES_JUDICIALES",1400000]

{"sheet":"CUMPLIMIENTO","index":3,"n_rows":16,"n_cols":2,"rows_kept":16,"cut":false,"hidden":false,"merged":[]}
["Columna1","Columna2"]
["L.O.B.","ESTATALES"]
["AMPARO","E. POSTCONTRACTUALES"]
["PARTICIPACIÓN COMPAÑÍA COASEGURO CEDIDO",1]
["VALOR ASEGURADO TOTAL",6607893483]
["VALOR ASEGURADO AMPARO",2243308670]
["VALOR PRETENSIÓN VALIDADA"]
["PML",{"$f":"MIN(B6,B7)","v":2243308670}]
["UMBRAL",{"$f":"IF(B3=\"E. CONTRACTUALES\",Hoja3!A12,IF(B3=\"E. POSTCONTRACTUALES\",Hoja3!B12,IF(B3=\"P. CONTRACTUALES\",Hoja3!C12,IF(B3=\"P. POSTCONTRACTUALES\",Hoja3!D12,IF(B3=\"S. CONTRACTUALES\",Hoja3!E12,IF(B3=\"S. POSTCONTRACTUALES\",Hoja3!F12,IF(B3=\"DISP_LEGALES\",Hoja3!G12,IF(B3=\"CAUCIONES_JUDICIALES\",Hoja3!H12))))))))","v":15792651847}]
["ATÍPICO?",{"$f":"IF(B7=\"\",\"NO\",IF(B8>B9,\"SI\",\"NO\"))","v":"NO"}]
["RESERVA ATÍPICO",{"$f":"IF(AND(B10=\"SI\",B3=\"E. CONTRACTUALES\"),B8*0.1074,IF(AND(B10=\"SI\",B3=\"E. POSTCONTRACTUALES\"),B8*0.1074,IF(AND(B10=\"SI\",B3=\"P. CONTRACTUALES\"),B8*0.1059,IF(AND(B10=\"SI\",B3=\"P. POSTCONTRACTUALES\"),B8*0.1059,IF(AND(B10=\"SI\",B3=\"S. CONTRACTUALES\"),B8*0.2965,IF(AND(B10=\"SI\",B3=\"S. POSTCONTRACTUALES\"),B8*0.2965,IF(AND(B10=\"SI\",B3=\"DISP_LEGALES\"),B8*0.4282,IF(AND(B10=\"SI\",B3=\"CAUCIONES_JUDICIALES\"),B8*0.2965))))))))","v":false}]
["CATE. VALOR ASEGURADO",{"$f":"IF(AND(B10=\"NO\",B3=\"E. CONTRACTUALES\",B5<=Hoja3!C18),\"BAJO\",IF(AND(B10=\"NO\",B3=\"E. CONTRACTUALES\",AND(B5>=Hoja3!D18),B5<=Hoja3!E18),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"E. CONTRACTUALES\",B5>=Hoja3!F18),\"ALTO\",IF(AND(B10=\"NO\",B3=\"E. POSTCONTRACTUALES\",B5<=Hoja3!C19),\"BAJO\",IF(AND(B10=\"NO\",B3=\"E. POSTCONTRACTUALES\",AND(B5>Hoja3!D19),B5<=Hoja3!E19),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"E. POSTCONTRACTUALES\",B5>Hoja3!F19),\"ALTO\",IF(AND(B10=\"NO\",B3=\"P. CONTRACTUALES\",B5<=Hoja3!C20),\"BAJO\",IF(AND(B10=\"NO\",B3=\"P. CONTRACTUALES\",AND(B5>=Hoja3!D20),B5<=Hoja3!E20),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"P. CONTRACTUALES\",B5>=Hoja3!F20),\"ALTO\",IF(AND(B10=\"NO\",B3=\"P. POSTCONTRACTUALES\",B5<=Hoja3!C21),\"BAJO\",IF(AND(B10=\"NO\",B3=\"P. POSTCONTRACTUALES\",AND(B5>=Hoja3!D21),B5<=Hoja3!E21),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"P. POSTCONTRACTUALES\",B5>=Hoja3!F21),\"ALTO\",IF(AND(B10=\"NO\",B3=\"S. CONTRACTUALES\",B5<=Hoja3!C22),\"BAJO\",IF(AND(B10=\"NO\",B3=\"S. CONTRACTUALES\",AND(B5>=Hoja3!D22),B5<=Hoja3!E22),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"S. CONTRACTUALES\",B5>=Hoja3!F22),\"ALTO\",IF(AND(B10=\"NO\",B3=\"S. POSTCONTRACTUALES\",B5<=Hoja3!C23),\"BAJO\",IF(AND(B10=\"NO\",B3=\"S. POSTCONTRACTUALES\",AND(B5>=Hoja3!D23),B5<=Hoja3!E23),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"S. POSTCONTRACTUALES\",B5>=Hoja3!F23),\"ALTO\",IF(AND(B10=\"NO\",B3=\"DISP_LEGALES\",B5<=Hoja3!C24),\"BAJO\",IF(AND(B10=\"NO\",B3=\"DISP_LEGALES\",AND(B5>=Hoja3!D24),B5<=Hoja3!E24),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"DISP_LEGALES\",B5>=Hoja3!F24),\"ALTO\",IF(AND(B10=\"NO\",B3=\"CAUCIONES_JUDICIALES\",B5<=Hoja3!C25),\"BAJO\",IF(AND(B10=\"NO\",B3=\"CAUCIONES_JUDICIALES\",AND(B5>=Hoja3!D25),B5<=Hoja3!E25),\"MEDIO\",IF(AND(B10=\"NO\",B3=\"CAUCIONES_JUDICIALES\",B5>=Hoja3!F25),\"ALTO\"))))))))))))))))))))))))","v":"ALTO"}]
["RESERVA TÍPICO PARTICIPACIÓN COMPAÑÍA",{"$f":"IF(AND(B3=\"E. CONTRACTUALES\",B12=\"BAJO\"),Hoja3!B31,IF(AND(B3=\"E. CONTRACTUALES\",B12=\"MEDIO\"),Hoja3!C31,IF(AND(B3=\"E. CONTRACTUALES\",B12=\"ALTO\"),Hoja3!D31,IF(AND(B3=\"E. POSTCONTRACTUALES\",B12=\"BAJO\"),Hoja3!B32,IF(AND(B3=\"E. POSTCONTRACTUALES\",B12=\"MEDIO\"),Hoja3!C32,IF(AND(B3=\"E. POSTCONTRACTUALES\",B12=\"ALTO\"),Hoja3!D32,IF(AND(B3=\"P. CONTRACTUALES\",B12=\"BAJO\"),Hoja3!B33,IF(AND(B3=\"P. CONTRACTUALES\",B12=\"MEDIO\"),Hoja3!C33,IF(AND(B3=\"P. CONTRACTUALES\",B12=\"ALTO\"),Hoja3!D33,IF(AND(B3=\"P. POSTCONTRACTUALES\",B12=\"BAJO\"),Hoja3!B34,IF(AND(B3=\"P. POSTCONTRACTUALES\",B12=\"MEDIO\"),Hoja3!C34,IF(AND(B3=\"P. POSTCONTRACTUALES\",B12=\"ALTO\"),Hoja3!D34,IF(AND(B3=\"S. CONTRACTUALES\",B12=\"BAJO\"),Hoja3!B35,IF(AND(B3=\"S. CONTRACTUALES\",B12=\"MEDIO\"),Hoja3!C35,IF(AND(B3=\"S. CONTRACTUALES\",B12=\"ALTO\"),Hoja3!D35,IF(AND(B3=\"S. POSTCONTRACTUALES\",B12=\"BAJO\"),Hoja3!B36,IF(AND(B3=\"S. POSTCONTRACTUALES\",B12=\"MEDIO\"),Hoja3!C36,IF(AND(B3=\"S. POSTCONTRACTUALES\",B12=\"ALTO\"),Hoja3!D36,IF(AND(B3=\"DISP_LEGALES\",B12=\"BAJO\"),Hoja3!B37,IF(AND(B3=\"DISP_LEGALES\",B12=\"MEDIO\"),Hoja3!C37,IF(AND(B3=\"DISP_LEGALES\",B12=\"ALTO\"),Hoja3!D37,IF(AND(B3=\"CAUCIONES_JUDICIALES\",B12=\"BAJO\"),Hoja3!B38,IF(AND(B3=\"CAUCIONES_JUDICIALES\",B12=\"MEDIO\"),Hoja3!C38,IF(AND(B3=\"CAUCIONES_JUDICIALES\",B12=\"ALTO\"),Hoja3!D38))))))))))))))))))))))))","v":67000000}]
["RESERVA SINIESTRO TÍPICO AL 100%",{"$f":"B13/B4","v":67000000}]
["RESERVA TÍPICO ALAE PARTICIPACIÓN COMPAÑÍA",{"$f":"IF(B3=\"E. CONTRACTUALES\",Hoja3!B44,IF(B3=\"E. POSTCONTRACTUALES\",Hoja3!B45,IF(B3=\"P. CONTRACTUALES\",Hoja3!B46,IF(B3=\"P. POSTCONTRACTUALES\",Hoja3!B47,IF(B3=\"S. CONTRACTUALES\",Hoja3!B48,IF(B3=\"S. POSTCONTRACTUALES\",Hoja3!B49,IF(B3=\"DISP_LEGALES\",Hoja3!B50,IF(B3=\"CAUCIONES_JUDICIALES\",Hoja3!B51))))))))","v":300000}]
["RESERVA ALAE TÍPICO AL 100%",{"$f":"B15/B4","v":300000}]